{"id":2063,"date":"2019-02-05T16:01:39","date_gmt":"2019-02-05T16:01:39","guid":{"rendered":"http:\/\/le-nomade.com\/nomade\/?p=2063"},"modified":"2019-02-05T16:03:19","modified_gmt":"2019-02-05T16:03:19","slug":"la-fin-annoncee-de-google","status":"publish","type":"post","link":"http:\/\/le-nomade.com\/nomade\/blog\/la-fin-annoncee-de-google\/","title":{"rendered":"La fin annonc\u00e9e de Google+"},"content":{"rendered":"<h2>Google + arr\u00eate ses activit\u00e9s en 2019<\/h2>\n<p>Nous avons re\u00e7u la confirmation en f\u00e9vrier 2019 de la part de Google de la fin du r\u00e9seau social de la firme bien connue.<\/p>\n<p>Voir le d\u00e9tail ci-bas :<\/p>\n<blockquote><p>En d\u00e9cembre\u00a02018, nous vous\u00a0<a href=\"https:\/\/blog.google\/technology\/safety-security\/expediting-changes-google-plus\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/blog.google\/technology\/safety-security\/expediting-changes-google-plus&amp;source=gmail&amp;ust=1549460004456000&amp;usg=AFQjCNGmOisQP_hzFAo6jzE5Iby2qTtDWQ\">avons annonc\u00e9<\/a>\u00a0notre d\u00e9cision de mettre fin, en avril\u00a02019, \u00e0 la version grand public de Google+ en raison de sa faible utilisation et des difficult\u00e9s li\u00e9es \u00e0 la gestion d&rsquo;un produit qui r\u00e9ponde pleinement aux attentes de ses utilisateurs. Nous vous remercions d&rsquo;avoir fait partie de l&rsquo;aventure Google+. Ce message va vous expliquer les prochaines \u00e9tapes, par exemple la marche \u00e0 suivre pour t\u00e9l\u00e9charger vos photos et autres contenus.<\/p><\/blockquote>\n<blockquote><p><b>Le 2\u00a0avril, nous commencerons \u00e0 supprimer le contenu des comptes Google+ personnels, et votre compte Google+ et toutes les pages Google+ que vous avez cr\u00e9\u00e9es ne seront plus disponibles<\/b>.<\/p>\n<p>&nbsp;<\/p>\n<p>Les photos et les vid\u00e9os associ\u00e9es \u00e0 ce service stock\u00e9es dans vos albums archiv\u00e9s et publi\u00e9es sur vos pages Google+, seront \u00e9galement supprim\u00e9es. Pour conserver ce contenu, assurez-vous de\u00a0<a href=\"https:\/\/support.google.com\/plus\/answer\/1045788\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/support.google.com\/plus\/answer\/1045788&amp;source=gmail&amp;ust=1549460004456000&amp;usg=AFQjCNGpxSLU9-8sTFo5yt7odr2zARuZVA\">le t\u00e9l\u00e9charger et de l&rsquo;enregistrer<\/a>\u00a0avant avril. Notez que les photos et les vid\u00e9os sauvegard\u00e9es dans Google\u00a0Photos ne seront pas supprim\u00e9es.<\/p>\n<p>Le processus de suppression du contenu des comptes Google+ grand public, des pages Google+ et des albums archiv\u00e9s durera quelques mois. Ce contenu pourra rester visible pendant cette p\u00e9riode. Par exemple, les utilisateurs pourront toujours voir des parties de leur compte Google+ via le journal d&rsquo;activit\u00e9 et certains contenus Google+ grand public pourront rester visibles pour les utilisateurs de G\u00a0Suite jusqu&rsquo;\u00e0 la suppression de Google+ grand public.<\/p><\/blockquote>\n<blockquote><p><b>D\u00e8s le 4\u00a0f\u00e9vrier, vous ne serez plus en mesure de cr\u00e9er de profils, pages, communaut\u00e9s ou \u00e9v\u00e9nements Google+.<\/b><\/p>\n<p>Pour plus de d\u00e9tails et d&rsquo;informations sur les prochaines \u00e9tapes jusqu&rsquo;\u00e0 l&rsquo;arr\u00eat du service, consultez les\u00a0<a href=\"https:\/\/support.google.com\/plus\/answer\/9217723\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/support.google.com\/plus\/answer\/9217723&amp;source=gmail&amp;ust=1549460004456000&amp;usg=AFQjCNH2hbhowu2Ac0KwOVra6_2FI_Wj7Q\">questions fr\u00e9quentes<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Si vous \u00eates propri\u00e9taire ou mod\u00e9rateur d&rsquo;une communaut\u00e9 Google+<\/b>, vous pouvez\u00a0<a href=\"https:\/\/support.google.com\/plus\/answer\/1045788\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/support.google.com\/plus\/answer\/1045788&amp;source=gmail&amp;ust=1549460004456000&amp;usg=AFQjCNGpxSLU9-8sTFo5yt7odr2zARuZVA\">t\u00e9l\u00e9charger et enregistrer<\/a>\u00a0les donn\u00e9es de cette communaut\u00e9\u00a0Google+. D\u00e8s le d\u00e9but du mois de mars\u00a02019, vous pourrez t\u00e9l\u00e9charger d&rsquo;autres donn\u00e9es, dont celles relatives aux auteurs et au contenu des articles d&rsquo;une communaut\u00e9 publique, ainsi que les photos associ\u00e9es.\u00a0<a href=\"https:\/\/support.google.com\/plus\/answer\/1045788#communities\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/support.google.com\/plus\/answer\/1045788%23communities&amp;source=gmail&amp;ust=1549460004456000&amp;usg=AFQjCNFAtIxY_Pg4FKFFHmXp_NE23t0ZRg\">En savoir plus<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><b>Si vous vous connectez \u00e0 des sites et \u00e0 des applications \u00e0 l&rsquo;aide du bouton Google+\u00a0Sign-in<\/b>, notez que ce bouton cessera de fonctionner au cours des prochaines semaines, mais qu&rsquo;il pourra, dans certains cas, \u00eatre remplac\u00e9 par un bouton Google\u00a0Sign-in. Partout o\u00f9 vous verrez le bouton Google\u00a0Sign-in, vous pourrez toujours vous connecter \u00e0 votre compte\u00a0Google.\u00a0<a href=\"https:\/\/support.google.com\/plus\/answer\/9217723#signin\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/support.google.com\/plus\/answer\/9217723%23signin&amp;source=gmail&amp;ust=1549460004456000&amp;usg=AFQjCNE8NxLJXnGm-E2PS1omoTjpoDsrSQ\">En savoir plus\u00a0<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><b>Si vous utilisiez Google+ pour laisser des commentaires sur votre propre site ou d&rsquo;autres sites<\/b>, notez que cette fonctionnalit\u00e9 sera supprim\u00e9e de Blogger d&rsquo;ici le 4\u00a0f\u00e9vrier, et des autres sites d&rsquo;ici le 7\u00a0mars. Tous vos commentaires Google+, quels que soient les sites concern\u00e9s, seront supprim\u00e9s \u00e0 partir du 2\u00a0avril\u00a02019.\u00a0<a href=\"https:\/\/support.google.com\/plus\/answer\/9217723#blogger\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/support.google.com\/plus\/answer\/9217723%23blogger&amp;source=gmail&amp;ust=1549460004456000&amp;usg=AFQjCNHQ01LH42CXt6TnSD5aENYTht-Nbw\">En savoir plus<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><b>Si vous utilisez G\u00a0Suite<\/b>, votre compte Google+ pour G\u00a0Suite restera actif. Pour en savoir plus, contactez votre\u00a0<a href=\"https:\/\/support.google.com\/a\/answer\/6208960\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/support.google.com\/a\/answer\/6208960&amp;source=gmail&amp;ust=1549460004457000&amp;usg=AFQjCNEVyn1UqARXmpS03j3JQVhBp985uQ\">administrateur G\u00a0Suite<\/a>. Vous devriez \u00e9galement d\u00e9couvrir bient\u00f4t un nouveau look et de nouvelles fonctionnalit\u00e9s.\u00a0<a href=\"https:\/\/cloud.google.com\/blog\/products\/g-suite\/new-enterprise-grade-features-in-googleplus-help-businesses-drive-collaboration\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/cloud.google.com\/blog\/products\/g-suite\/new-enterprise-grade-features-in-googleplus-help-businesses-drive-collaboration&amp;source=gmail&amp;ust=1549460004457000&amp;usg=AFQjCNHkVH6xNAzTK6rprqRnI53PKadHNQ\">En savoir plus<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><b>Si vous d\u00e9veloppez des applications<\/b>\u00a0\u00e0 l&rsquo;aide des API Google+ ou de Google+\u00a0Sign-In,\u00a0<a href=\"https:\/\/developers.google.com\/+\/api-shutdown\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/developers.google.com\/%2B\/api-shutdown&amp;source=gmail&amp;ust=1549460004457000&amp;usg=AFQjCNFDiCp55q3iMfpNAXpxLc30ZpcgRw\">cliquez ici<\/a>\u00a0pour d\u00e9couvrir quel impact cela aura sur votre travail.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Google + arr\u00eate ses activit\u00e9s en 2019 Nous avons re\u00e7u la confirmation en f\u00e9vrier 2019 de la part de Google<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,35,36,6,18],"tags":[62],"_links":{"self":[{"href":"http:\/\/le-nomade.com\/nomade\/wp-json\/wp\/v2\/posts\/2063"}],"collection":[{"href":"http:\/\/le-nomade.com\/nomade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/le-nomade.com\/nomade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/le-nomade.com\/nomade\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/le-nomade.com\/nomade\/wp-json\/wp\/v2\/comments?post=2063"}],"version-history":[{"count":3,"href":"http:\/\/le-nomade.com\/nomade\/wp-json\/wp\/v2\/posts\/2063\/revisions"}],"predecessor-version":[{"id":2066,"href":"http:\/\/le-nomade.com\/nomade\/wp-json\/wp\/v2\/posts\/2063\/revisions\/2066"}],"wp:attachment":[{"href":"http:\/\/le-nomade.com\/nomade\/wp-json\/wp\/v2\/media?parent=2063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/le-nomade.com\/nomade\/wp-json\/wp\/v2\/categories?post=2063"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/le-nomade.com\/nomade\/wp-json\/wp\/v2\/tags?post=2063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}